{"id":974,"date":"2011-12-12T16:18:19","date_gmt":"2011-12-12T16:18:19","guid":{"rendered":"http:\/\/montehorizonte.com\/PT\/?p=974"},"modified":"2020-07-06T11:49:13","modified_gmt":"2020-07-06T10:49:13","slug":"vivenda-isolada-para-ferias-no-alentejo","status":"publish","type":"post","link":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/","title":{"rendered":"Vivenda isolada para F\u00e9rias no Alentejo"},"content":{"rendered":"<p><strong>Vivenda isolada com Piscina para F\u00e9rias no Alentejo &#8211; Casa Sobreiro<\/strong><\/p>\n<p>Ocupa\u00e7\u00e3o m\u00e1xima de 4 pessoas. Pre\u00e7os a partir de 119 euros por noite para 2 pessoas.<\/p>\n<p style=\"text-align: center;\">Monte Horizonte \u00e9 um lugar \u00fanico onde o espa\u00e7o, a tranquilidade e o respeito pela natureza e uns pelos outros s\u00e3o centrais. Para continuar a garantir este sentimento, as crian\u00e7as com menos de 7 anos n\u00e3o s\u00e3o permitidas a partir de 1 de janeiro de 2019.<\/p>\n<p style=\"text-align: center;\"><div id=\"metaslider-id-3039\" style=\"max-width: 1024px;\" class=\"ml-slider-3-110-0 metaslider metaslider-nivo metaslider-3039 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Casa Sobreiro\" data-height=\"576\" data-width=\"1024\">\n    <div id=\"metaslider_container_3039\">\n        <div class='slider-wrapper theme-default'><div class='ribbon'><\/div><div id='metaslider_3039' class='nivoSlider'><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-2-1.jpg\" height=\"576\" width=\"1024\" data-caption=\"Terra&ccedil;o\" title=\"Casa-Sobreiro-2-1\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3871 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Pool-3.jpg\" height=\"576\" width=\"1024\" data-caption=\"Piscina\" title=\"Piscina F\u00e9rias em Monte Horizonte em Portugal\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3749 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Overview-Monte-Horizonte-sobreiro-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Localiza&ccedil;&atilde;o\" title=\"Localiza\u00e7\u00e3o Monte Horizonte Casa Sobreiro\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3585 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Living-Room-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Sala\" title=\"Casa Sobreiro F\u00e9rias em Monte Horizonte em Portugal\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3593 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Bedroom1-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Quarto 1\" title=\"Casa Sobreiro F\u00e9rias em Monte Horizonte em Portugal\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3597 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Living-Room-1-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Sala\" title=\"Casa Sobreiro F\u00e9rias em Monte Horizonte em Portugal\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3594 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Bedroom2-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Quarto 2\" title=\"Casa Sobreiro F\u00e9rias em Monte Horizonte em Portugal\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3596 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Casa-de-banho-1-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Casa de Banho\" title=\"Monte Horizonte - Casa Sobreiro - Casa de Banho\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3671 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Cozinha-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Cozinha\" title=\"Casa Sobreiro - Cozinha\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3282 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Terrace-1-1.jpg\" height=\"576\" width=\"1024\" data-caption=\"Casa Sobreiro\" title=\"Casa-Sobreiro-Terrace-1-1\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3682 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Zwembad-Handdoeken.jpg\" height=\"576\" width=\"1024\" data-caption=\"Toalhas de Piscina\" title=\"F\u00e9rias em Monte Horizonte em Portugal Toalhas de Piscina\" alt=\"F\u00e9rias em Monte Horizonte em Portugal Toalhas de Piscina\" class=\"slider-3039 slide-3672 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Pool-4-2.jpg\" height=\"576\" width=\"1024\" data-caption=\"Piscina\" title=\"Piscina F\u00e9rias em Monte Horizonte em Portugal\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3687 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Salamandra-1024x576.jpg\" height=\"576\" width=\"1024\" data-caption=\"Salamandra\" title=\"Salamandra\" alt=\"Casa Mimosa Salamandra F\u00e9rias no Alenejo\" class=\"slider-3039 slide-3865 msDefaultImage\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Casa-Sobreiro-Terrace-1.jpg\" height=\"576\" width=\"1024\" data-caption=\"Terra&ccedil;o\" title=\"Casa-Sobreiro-Terrace-1\" alt=\"F\u00e9rias em Monte Horizonte em Portugal\" class=\"slider-3039 slide-3931 msDefaultImage\" \/><\/div><\/div>\n        \n    <\/div>\n<\/div>\n<p>Esta vivenda de f\u00e9rias destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.<\/p>\n<p>Possui um sistema de televis\u00e3o sat\u00e9lite com acesso a canais tais como CNN, etc. Na sala h\u00e1 um fog\u00e3o a lenha para poss\u00edvel aquecimento nos meses de inverno. Na sala de estar h\u00e1 um sof\u00e1-cama para 1 pessoa.<\/p>\n<p>Nos meses mais frios de novembro a mar\u00e7o, cobramos 35 euros por semana pela madeira do fog\u00e3o a lenha. Se houver necessidade de aquecimento de madeira em outro per\u00edodo, os custos s\u00e3o de 5 euros por dia.<\/p>\n<p>Um quarto tem cama de casal e o outro quarto tem 2 camas de solteiro com roupa de cama. A roupa de cama \u00e9 trocada uma vez por semana e as toalhas duas vezes por semana.<\/p>\n<p>Cada 3 casas tem um churrasco grande comum, que est\u00e1 localizado central, entre as casas.<\/p>\n<p>Se desejar, o pequeno-almo\u00e7o pode ser entregue \u00e0 sua porta por um custo adicional.<\/p>\n<p>No alpendre encontram-se cadeiras e mesa para que desfrute das vistas maravilhosas.<\/p>\n<p>Na moradia de f\u00e9rias ainda se encontra um mapa documentado com informa\u00e7\u00e3o acerca da zona circundante.<\/p>\n<p>Para encontrar nossos pre\u00e7os por dia mova o rato ou o dedo pelas datas no calend\u00e1rio de disponibilidade em baixo. Voc\u00ea ver\u00e1 os pre\u00e7os por dia. Se voc\u00ea selecionar um per\u00edodo, o pre\u00e7o total ser\u00e1 exibido.<\/p>\n<p>Sua reserva inclui:<br \/>\n\u2022 Roupa de cama limpa uma vez por semana.<br \/>\n\u2022 Toalhas limpas e roupas de cozinha duas vezes por semana.<br \/>\n\u2022 Toalhas de praia e piscina (1,4 x 1,9 metros)<br \/>\n\u2022 Caf\u00e9 e ch\u00e1 ilimitados<br \/>\n\u2022 Papel higi\u00eanico<br \/>\n\u2022 Sab\u00e3o e shampoo<br \/>\n\u2022 Azeite e vinagre<br \/>\n\u2022 Sal e pimenta<\/p>\n<p>A nossa disponibilidade \u00e9 sempre atualizado e voc\u00ea pode v\u00ea-lo abaixo. Se voc\u00ea quiser fazer uma reserva clique na data em que as suas f\u00e9rias come\u00e7a no formul\u00e1rio abaixo. Voc\u00ea tamb\u00e9m pode fazer uma reserva por e-mail.<\/p>\n<p><script type=\"text\/javascript\" src=\"https:\/\/montehorizonte.com\/script\/index.php?controller=pjFront&#038;action=pjActionLoad&#038;cid=7&#038;view=12&#038;locale=3\"><\/script><\/p>\n<p>F\u00e9rias no Alentejo perto da praia. Sil\u00eancio total.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivenda isolada com Piscina para F\u00e9rias no Alentejo &#8211; Casa Sobreiro Ocupa\u00e7\u00e3o m\u00e1xima de 4 pessoas. Pre\u00e7os a partir de 119 euros por noite para 2 pessoas. Monte Horizonte \u00e9 um lugar \u00fanico onde o espa\u00e7o, a tranquilidade e o respeito pela natureza e uns pelos outros s\u00e3o centrais. Para continuar a garantir este sentimento,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[6,95,45,83,5,43,78,10,46,42],"class_list":["post-974","post","type-post","status-publish","format-standard","hentry","category-information","tag-alentejo","tag-casa-isolada","tag-casas-de-campo","tag-espaco","tag-ferias","tag-isolada","tag-natureza","tag-praia","tag-turismo-rural","tag-vivenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta vivenda destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"keywords\" content=\"vivenda,isolada,ferias,alentejo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"montehorizonte.com\/PT\/\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vivenda isolada para F\u00e9rias no Alentejo\" \/>\n\t\t<meta property=\"og:description\" content=\"Esta vivenda destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Pool-3.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Pool-3.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-12-12T16:18:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-07-06T10:49:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/montehorizonte\/\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#article\",\"name\":\"Vivenda isolada para F\\u00e9rias no Alentejo\",\"headline\":\"Vivenda isolada para F\\u00e9rias no Alentejo\",\"author\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/wp-content\\\/uploads\\\/Logo.jpg\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/#articleImage\",\"width\":721,\"height\":536,\"caption\":\"Monte Horizonte\"},\"datePublished\":\"2011-12-12T16:18:19+00:00\",\"dateModified\":\"2020-07-06T11:49:13+01:00\",\"inLanguage\":\"pt-PT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#webpage\"},\"articleSection\":\"Information, alentejo, casa isolada, casas de campo, espa\\u00e7o, f\\u00e9rias, isolada, natureza, Praia, turismo rural, vivenda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/montehorizonte.com\\\/PT\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/category\\\/information\\\/#listItem\",\"name\":\"Information\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/category\\\/information\\\/#listItem\",\"position\":2,\"name\":\"Information\",\"item\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/category\\\/information\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#listItem\",\"name\":\"Vivenda isolada para F\\u00e9rias no Alentejo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#listItem\",\"position\":3,\"name\":\"Vivenda isolada para F\\u00e9rias no Alentejo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/category\\\/information\\\/#listItem\",\"name\":\"Information\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/#organization\",\"name\":\"Monte Horizonte\",\"description\":\"\\u00c9 tudo sobre Sil\\u00eancio, Privacidade, Tranquilidade, Estrelas, Praia e Natureza.\",\"url\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/\",\"telephone\":\"+351269825383\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/wp-content\\\/uploads\\\/Logo.jpg\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#organizationLogo\",\"width\":721,\"height\":536,\"caption\":\"Monte Horizonte\"},\"image\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/montehorizonte\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d92a8e532b9d73b6df29d9163a7cfa3ce40aa3f46bd430c1e62c667e8a0ccfee?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#webpage\",\"url\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/\",\"name\":\"Vivenda isolada para F\\u00e9rias no Alentejo\",\"description\":\"Esta vivenda destacada \\u00e9 composta por sala, 2 quartos, uma cozinha com fog\\u00e3o a g\\u00e1s e frigor\\u00edfico. A casa de banho tem duche, sanita, bid\\u00ea e lavat\\u00f3rio.\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/vivenda-isolada-para-ferias-no-alentejo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2011-12-12T16:18:19+00:00\",\"dateModified\":\"2020-07-06T11:49:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/#website\",\"url\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/\",\"name\":\"Monte Horizonte - Turismo Rural - Casas Isoladas - Eco & Nature\",\"description\":\"\\u00c9 tudo sobre Sil\\u00eancio, Privacidade, Tranquilidade, Estrelas, Praia e Natureza.\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/montehorizonte.com\\\/PT\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Vivenda isolada para F\u00e9rias no Alentejo","description":"Esta vivenda destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.","canonical_url":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/","robots":"max-image-preview:large","keywords":"vivenda,isolada,ferias,alentejo","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#article","name":"Vivenda isolada para F\u00e9rias no Alentejo","headline":"Vivenda isolada para F\u00e9rias no Alentejo","author":{"@id":"https:\/\/montehorizonte.com\/PT\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/montehorizonte.com\/PT\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Logo.jpg","@id":"https:\/\/montehorizonte.com\/PT\/#articleImage","width":721,"height":536,"caption":"Monte Horizonte"},"datePublished":"2011-12-12T16:18:19+00:00","dateModified":"2020-07-06T11:49:13+01:00","inLanguage":"pt-PT","mainEntityOfPage":{"@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#webpage"},"isPartOf":{"@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#webpage"},"articleSection":"Information, alentejo, casa isolada, casas de campo, espa\u00e7o, f\u00e9rias, isolada, natureza, Praia, turismo rural, vivenda"},{"@type":"BreadcrumbList","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT#listItem","position":1,"name":"Home","item":"https:\/\/montehorizonte.com\/PT","nextItem":{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT\/category\/information\/#listItem","name":"Information"}},{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT\/category\/information\/#listItem","position":2,"name":"Information","item":"https:\/\/montehorizonte.com\/PT\/category\/information\/","nextItem":{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#listItem","name":"Vivenda isolada para F\u00e9rias no Alentejo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#listItem","position":3,"name":"Vivenda isolada para F\u00e9rias no Alentejo","previousItem":{"@type":"ListItem","@id":"https:\/\/montehorizonte.com\/PT\/category\/information\/#listItem","name":"Information"}}]},{"@type":"Organization","@id":"https:\/\/montehorizonte.com\/PT\/#organization","name":"Monte Horizonte","description":"\u00c9 tudo sobre Sil\u00eancio, Privacidade, Tranquilidade, Estrelas, Praia e Natureza.","url":"https:\/\/montehorizonte.com\/PT\/","telephone":"+351269825383","logo":{"@type":"ImageObject","url":"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Logo.jpg","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#organizationLogo","width":721,"height":536,"caption":"Monte Horizonte"},"image":{"@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/montehorizonte\/"]},{"@type":"Person","@id":"https:\/\/montehorizonte.com\/PT\/author\/admin\/#author","url":"https:\/\/montehorizonte.com\/PT\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d92a8e532b9d73b6df29d9163a7cfa3ce40aa3f46bd430c1e62c667e8a0ccfee?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#webpage","url":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/","name":"Vivenda isolada para F\u00e9rias no Alentejo","description":"Esta vivenda destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/montehorizonte.com\/PT\/#website"},"breadcrumb":{"@id":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/#breadcrumblist"},"author":{"@id":"https:\/\/montehorizonte.com\/PT\/author\/admin\/#author"},"creator":{"@id":"https:\/\/montehorizonte.com\/PT\/author\/admin\/#author"},"datePublished":"2011-12-12T16:18:19+00:00","dateModified":"2020-07-06T11:49:13+01:00"},{"@type":"WebSite","@id":"https:\/\/montehorizonte.com\/PT\/#website","url":"https:\/\/montehorizonte.com\/PT\/","name":"Monte Horizonte - Turismo Rural - Casas Isoladas - Eco & Nature","description":"\u00c9 tudo sobre Sil\u00eancio, Privacidade, Tranquilidade, Estrelas, Praia e Natureza.","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/montehorizonte.com\/PT\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"montehorizonte.com\/PT\/","og:type":"article","og:title":"Vivenda isolada para F\u00e9rias no Alentejo","og:description":"Esta vivenda destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.","og:url":"https:\/\/montehorizonte.com\/PT\/vivenda-isolada-para-ferias-no-alentejo\/","og:image":"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Pool-3.jpg","og:image:secure_url":"https:\/\/montehorizonte.com\/PT\/wp-content\/uploads\/Pool-3.jpg","og:image:width":1024,"og:image:height":576,"article:published_time":"2011-12-12T16:18:19+00:00","article:modified_time":"2020-07-06T10:49:13+00:00","article:publisher":"https:\/\/www.facebook.com\/montehorizonte\/"},"aioseo_meta_data":{"post_id":"974","title":"Vivenda isolada para F\u00e9rias no Alentejo","description":"Esta vivenda destacada \u00e9 composta por sala, 2 quartos, uma cozinha com fog\u00e3o a g\u00e1s e frigor\u00edfico. A casa de banho tem duche, sanita, bid\u00ea e lavat\u00f3rio.","keywords":[{"label":"vivenda","value":"vivenda"},{"label":"isolada","value":"isolada"},{"label":"ferias","value":"ferias"},{"label":"alentejo","value":"alentejo"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 05:57:20","updated":"2025-06-04 07:07:40","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/posts\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/comments?post=974"}],"version-history":[{"count":5,"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/posts\/974\/revisions"}],"predecessor-version":[{"id":3786,"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/posts\/974\/revisions\/3786"}],"wp:attachment":[{"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/categories?post=974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montehorizonte.com\/PT\/wp-json\/wp\/v2\/tags?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}